{"id":839,"date":"2022-11-10T17:46:40","date_gmt":"2022-11-10T16:46:40","guid":{"rendered":"https:\/\/asso-sozen.com\/?p=839"},"modified":"2024-12-01T13:47:46","modified_gmt":"2024-12-01T12:47:46","slug":"nos-partenaires","status":"publish","type":"post","link":"https:\/\/asso-sozen.com\/index.php\/2022\/11\/10\/nos-partenaires\/","title":{"rendered":"Nos Partenaires"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"250\" height=\"250\" src=\"https:\/\/asso-sozen.com\/wp-content\/uploads\/2024\/12\/Logo-Patchwork-Sept-2018.png\" alt=\"\" class=\"wp-image-1387\" style=\"width:158px;height:auto\" srcset=\"https:\/\/asso-sozen.com\/wp-content\/uploads\/2024\/12\/Logo-Patchwork-Sept-2018.png 250w, https:\/\/asso-sozen.com\/wp-content\/uploads\/2024\/12\/Logo-Patchwork-Sept-2018-150x150.png 150w\" sizes=\"(max-width: 250px) 100vw, 250px\" \/><\/figure>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full is-resized\"><img decoding=\"async\" width=\"180\" height=\"180\" src=\"https:\/\/asso-sozen.com\/wp-content\/uploads\/2024\/02\/images.jpg\" alt=\"\" class=\"wp-image-1184\" style=\"object-fit:cover;width:206px;height:auto\" srcset=\"https:\/\/asso-sozen.com\/wp-content\/uploads\/2024\/02\/images.jpg 180w, https:\/\/asso-sozen.com\/wp-content\/uploads\/2024\/02\/images-150x150.jpg 150w\" sizes=\"(max-width: 180px) 100vw, 180px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"224\" height=\"224\" src=\"https:\/\/asso-sozen.com\/wp-content\/uploads\/2022\/11\/logo-audrey-bartier.png\" alt=\"\" class=\"wp-image-840\" style=\"aspect-ratio:1;object-fit:cover\" srcset=\"https:\/\/asso-sozen.com\/wp-content\/uploads\/2022\/11\/logo-audrey-bartier.png 224w, https:\/\/asso-sozen.com\/wp-content\/uploads\/2022\/11\/logo-audrey-bartier-150x150.png 150w\" sizes=\"(max-width: 224px) 100vw, 224px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"245\" height=\"245\" src=\"https:\/\/asso-sozen.com\/wp-content\/uploads\/2022\/11\/logo-mairie-st-martin.png\" alt=\"\" class=\"wp-image-844\" srcset=\"https:\/\/asso-sozen.com\/wp-content\/uploads\/2022\/11\/logo-mairie-st-martin.png 245w, https:\/\/asso-sozen.com\/wp-content\/uploads\/2022\/11\/logo-mairie-st-martin-150x150.png 150w\" sizes=\"(max-width: 245px) 100vw, 245px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/asso-sozen.com\/wp-content\/uploads\/2022\/11\/logo-mariette.jpeg\" alt=\"\" class=\"wp-image-847\" style=\"aspect-ratio:1;object-fit:cover\" srcset=\"https:\/\/asso-sozen.com\/wp-content\/uploads\/2022\/11\/logo-mariette.jpeg 200w, https:\/\/asso-sozen.com\/wp-content\/uploads\/2022\/11\/logo-mariette-150x150.jpeg 150w\" sizes=\"(max-width: 200px) 100vw, 200px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"214\" height=\"235\" src=\"https:\/\/asso-sozen.com\/wp-content\/uploads\/2023\/01\/AMIE.png\" alt=\"\" class=\"wp-image-960\" style=\"aspect-ratio:1;object-fit:cover\"\/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"216\" height=\"216\" src=\"https:\/\/asso-sozen.com\/wp-content\/uploads\/2022\/11\/logo-idees-dEugenie.png\" alt=\"\" class=\"wp-image-845\" style=\"aspect-ratio:1;object-fit:cover\" srcset=\"https:\/\/asso-sozen.com\/wp-content\/uploads\/2022\/11\/logo-idees-dEugenie.png 216w, https:\/\/asso-sozen.com\/wp-content\/uploads\/2022\/11\/logo-idees-dEugenie-150x150.png 150w\" sizes=\"(max-width: 216px) 100vw, 216px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"733\" src=\"https:\/\/asso-sozen.com\/wp-content\/uploads\/2022\/11\/624d6469b1d2a384065559-1024x733.png\" alt=\"\" class=\"wp-image-1190\" style=\"aspect-ratio:1;object-fit:contain\" srcset=\"https:\/\/asso-sozen.com\/wp-content\/uploads\/2022\/11\/624d6469b1d2a384065559-1024x733.png 1024w, https:\/\/asso-sozen.com\/wp-content\/uploads\/2022\/11\/624d6469b1d2a384065559-300x215.png 300w, https:\/\/asso-sozen.com\/wp-content\/uploads\/2022\/11\/624d6469b1d2a384065559-768x549.png 768w, https:\/\/asso-sozen.com\/wp-content\/uploads\/2022\/11\/624d6469b1d2a384065559.png 1244w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"560\" height=\"293\" src=\"https:\/\/asso-sozen.com\/wp-content\/uploads\/2022\/11\/Sans-titre.png\" alt=\"\" class=\"wp-image-959\" style=\"aspect-ratio:4\/3;object-fit:contain\" srcset=\"https:\/\/asso-sozen.com\/wp-content\/uploads\/2022\/11\/Sans-titre.png 560w, https:\/\/asso-sozen.com\/wp-content\/uploads\/2022\/11\/Sans-titre-300x157.png 300w\" sizes=\"(max-width: 560px) 100vw, 560px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center\">Sp\u00e9cialiste dans le bien-\u00eatre des professionnels de sant\u00e9. Rendez vous sur le site <a href=\"http:\/\/www.happyworkers.fr\/\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>www.happyworkers.fr<\/strong><\/a><br><\/p>\n<\/div>\n<\/div>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sp\u00e9cialiste dans le bien-\u00eatre des professionnels de sant\u00e9. Rendez vous sur le site www.happyworkers.fr<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-839","post","type-post","status-publish","format-standard","hentry","category-pour-aller-plus-loin"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nos Partenaires - SO&#039;Zen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/asso-sozen.com\/index.php\/2022\/11\/10\/nos-partenaires\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nos Partenaires - SO&#039;Zen\" \/>\n<meta property=\"og:description\" content=\"Sp\u00e9cialiste dans le bien-\u00eatre des professionnels de sant\u00e9. Rendez vous sur le site www.happyworkers.fr\" \/>\n<meta property=\"og:url\" content=\"https:\/\/asso-sozen.com\/index.php\/2022\/11\/10\/nos-partenaires\/\" \/>\n<meta property=\"og:site_name\" content=\"SO&#039;Zen\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-10T16:46:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-01T12:47:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/asso-sozen.com\/wp-content\/uploads\/2024\/12\/Logo-Patchwork-Sept-2018.png\" \/>\n\t<meta property=\"og:image:width\" content=\"250\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"So\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"So\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/asso-sozen.com\\\/index.php\\\/2022\\\/11\\\/10\\\/nos-partenaires\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/asso-sozen.com\\\/index.php\\\/2022\\\/11\\\/10\\\/nos-partenaires\\\/\"},\"author\":{\"name\":\"So\",\"@id\":\"https:\\\/\\\/asso-sozen.com\\\/#\\\/schema\\\/person\\\/5447be38b9e8ec33a446c0273d8fdbdd\"},\"headline\":\"Nos Partenaires\",\"datePublished\":\"2022-11-10T16:46:40+00:00\",\"dateModified\":\"2024-12-01T12:47:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/asso-sozen.com\\\/index.php\\\/2022\\\/11\\\/10\\\/nos-partenaires\\\/\"},\"wordCount\":20,\"publisher\":{\"@id\":\"https:\\\/\\\/asso-sozen.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/asso-sozen.com\\\/index.php\\\/2022\\\/11\\\/10\\\/nos-partenaires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/asso-sozen.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Logo-Patchwork-Sept-2018.png\",\"articleSection\":[\"Pour aller plus loin\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/asso-sozen.com\\\/index.php\\\/2022\\\/11\\\/10\\\/nos-partenaires\\\/\",\"url\":\"https:\\\/\\\/asso-sozen.com\\\/index.php\\\/2022\\\/11\\\/10\\\/nos-partenaires\\\/\",\"name\":\"Nos Partenaires - SO&#039;Zen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/asso-sozen.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/asso-sozen.com\\\/index.php\\\/2022\\\/11\\\/10\\\/nos-partenaires\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/asso-sozen.com\\\/index.php\\\/2022\\\/11\\\/10\\\/nos-partenaires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/asso-sozen.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Logo-Patchwork-Sept-2018.png\",\"datePublished\":\"2022-11-10T16:46:40+00:00\",\"dateModified\":\"2024-12-01T12:47:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/asso-sozen.com\\\/index.php\\\/2022\\\/11\\\/10\\\/nos-partenaires\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/asso-sozen.com\\\/index.php\\\/2022\\\/11\\\/10\\\/nos-partenaires\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/asso-sozen.com\\\/index.php\\\/2022\\\/11\\\/10\\\/nos-partenaires\\\/#primaryimage\",\"url\":\"https:\\\/\\\/asso-sozen.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Logo-Patchwork-Sept-2018.png\",\"contentUrl\":\"https:\\\/\\\/asso-sozen.com\\\/wp-content\\\/uploads\\\/2024\\\/12\\\/Logo-Patchwork-Sept-2018.png\",\"width\":250,\"height\":250},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/asso-sozen.com\\\/index.php\\\/2022\\\/11\\\/10\\\/nos-partenaires\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/asso-sozen.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pour aller plus loin\",\"item\":\"https:\\\/\\\/asso-sozen.com\\\/index.php\\\/pour-aller-plus-loin\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Nos Partenaires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/asso-sozen.com\\\/#website\",\"url\":\"https:\\\/\\\/asso-sozen.com\\\/\",\"name\":\"SO&#039;Zen\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/asso-sozen.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/asso-sozen.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/asso-sozen.com\\\/#organization\",\"name\":\"SO&#039;Zen\",\"url\":\"https:\\\/\\\/asso-sozen.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/asso-sozen.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/asso-sozen.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-logoSOZEN512-2.png\",\"contentUrl\":\"https:\\\/\\\/asso-sozen.com\\\/wp-content\\\/uploads\\\/2020\\\/07\\\/cropped-logoSOZEN512-2.png\",\"width\":512,\"height\":289,\"caption\":\"SO&#039;Zen\"},\"image\":{\"@id\":\"https:\\\/\\\/asso-sozen.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/asso-sozen.com\\\/#\\\/schema\\\/person\\\/5447be38b9e8ec33a446c0273d8fdbdd\",\"name\":\"So\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7913ed250f4c60a074e6d05ee1fe40c01301d2c3f778709568abfc6ed402b848?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7913ed250f4c60a074e6d05ee1fe40c01301d2c3f778709568abfc6ed402b848?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7913ed250f4c60a074e6d05ee1fe40c01301d2c3f778709568abfc6ed402b848?s=96&d=mm&r=g\",\"caption\":\"So\"},\"url\":\"https:\\\/\\\/asso-sozen.com\\\/index.php\\\/author\\\/admin9093\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nos Partenaires - SO&#039;Zen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/asso-sozen.com\/index.php\/2022\/11\/10\/nos-partenaires\/","og_locale":"fr_FR","og_type":"article","og_title":"Nos Partenaires - SO&#039;Zen","og_description":"Sp\u00e9cialiste dans le bien-\u00eatre des professionnels de sant\u00e9. Rendez vous sur le site www.happyworkers.fr","og_url":"https:\/\/asso-sozen.com\/index.php\/2022\/11\/10\/nos-partenaires\/","og_site_name":"SO&#039;Zen","article_published_time":"2022-11-10T16:46:40+00:00","article_modified_time":"2024-12-01T12:47:46+00:00","og_image":[{"width":250,"height":250,"url":"https:\/\/asso-sozen.com\/wp-content\/uploads\/2024\/12\/Logo-Patchwork-Sept-2018.png","type":"image\/png"}],"author":"So","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"So","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/asso-sozen.com\/index.php\/2022\/11\/10\/nos-partenaires\/#article","isPartOf":{"@id":"https:\/\/asso-sozen.com\/index.php\/2022\/11\/10\/nos-partenaires\/"},"author":{"name":"So","@id":"https:\/\/asso-sozen.com\/#\/schema\/person\/5447be38b9e8ec33a446c0273d8fdbdd"},"headline":"Nos Partenaires","datePublished":"2022-11-10T16:46:40+00:00","dateModified":"2024-12-01T12:47:46+00:00","mainEntityOfPage":{"@id":"https:\/\/asso-sozen.com\/index.php\/2022\/11\/10\/nos-partenaires\/"},"wordCount":20,"publisher":{"@id":"https:\/\/asso-sozen.com\/#organization"},"image":{"@id":"https:\/\/asso-sozen.com\/index.php\/2022\/11\/10\/nos-partenaires\/#primaryimage"},"thumbnailUrl":"https:\/\/asso-sozen.com\/wp-content\/uploads\/2024\/12\/Logo-Patchwork-Sept-2018.png","articleSection":["Pour aller plus loin"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/asso-sozen.com\/index.php\/2022\/11\/10\/nos-partenaires\/","url":"https:\/\/asso-sozen.com\/index.php\/2022\/11\/10\/nos-partenaires\/","name":"Nos Partenaires - SO&#039;Zen","isPartOf":{"@id":"https:\/\/asso-sozen.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/asso-sozen.com\/index.php\/2022\/11\/10\/nos-partenaires\/#primaryimage"},"image":{"@id":"https:\/\/asso-sozen.com\/index.php\/2022\/11\/10\/nos-partenaires\/#primaryimage"},"thumbnailUrl":"https:\/\/asso-sozen.com\/wp-content\/uploads\/2024\/12\/Logo-Patchwork-Sept-2018.png","datePublished":"2022-11-10T16:46:40+00:00","dateModified":"2024-12-01T12:47:46+00:00","breadcrumb":{"@id":"https:\/\/asso-sozen.com\/index.php\/2022\/11\/10\/nos-partenaires\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/asso-sozen.com\/index.php\/2022\/11\/10\/nos-partenaires\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/asso-sozen.com\/index.php\/2022\/11\/10\/nos-partenaires\/#primaryimage","url":"https:\/\/asso-sozen.com\/wp-content\/uploads\/2024\/12\/Logo-Patchwork-Sept-2018.png","contentUrl":"https:\/\/asso-sozen.com\/wp-content\/uploads\/2024\/12\/Logo-Patchwork-Sept-2018.png","width":250,"height":250},{"@type":"BreadcrumbList","@id":"https:\/\/asso-sozen.com\/index.php\/2022\/11\/10\/nos-partenaires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/asso-sozen.com\/"},{"@type":"ListItem","position":2,"name":"Pour aller plus loin","item":"https:\/\/asso-sozen.com\/index.php\/pour-aller-plus-loin\/"},{"@type":"ListItem","position":3,"name":"Nos Partenaires"}]},{"@type":"WebSite","@id":"https:\/\/asso-sozen.com\/#website","url":"https:\/\/asso-sozen.com\/","name":"SO&#039;Zen","description":"","publisher":{"@id":"https:\/\/asso-sozen.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/asso-sozen.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/asso-sozen.com\/#organization","name":"SO&#039;Zen","url":"https:\/\/asso-sozen.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/asso-sozen.com\/#\/schema\/logo\/image\/","url":"https:\/\/asso-sozen.com\/wp-content\/uploads\/2020\/07\/cropped-logoSOZEN512-2.png","contentUrl":"https:\/\/asso-sozen.com\/wp-content\/uploads\/2020\/07\/cropped-logoSOZEN512-2.png","width":512,"height":289,"caption":"SO&#039;Zen"},"image":{"@id":"https:\/\/asso-sozen.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/asso-sozen.com\/#\/schema\/person\/5447be38b9e8ec33a446c0273d8fdbdd","name":"So","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/7913ed250f4c60a074e6d05ee1fe40c01301d2c3f778709568abfc6ed402b848?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7913ed250f4c60a074e6d05ee1fe40c01301d2c3f778709568abfc6ed402b848?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7913ed250f4c60a074e6d05ee1fe40c01301d2c3f778709568abfc6ed402b848?s=96&d=mm&r=g","caption":"So"},"url":"https:\/\/asso-sozen.com\/index.php\/author\/admin9093\/"}]}},"_links":{"self":[{"href":"https:\/\/asso-sozen.com\/index.php\/wp-json\/wp\/v2\/posts\/839","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/asso-sozen.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/asso-sozen.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/asso-sozen.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/asso-sozen.com\/index.php\/wp-json\/wp\/v2\/comments?post=839"}],"version-history":[{"count":25,"href":"https:\/\/asso-sozen.com\/index.php\/wp-json\/wp\/v2\/posts\/839\/revisions"}],"predecessor-version":[{"id":1390,"href":"https:\/\/asso-sozen.com\/index.php\/wp-json\/wp\/v2\/posts\/839\/revisions\/1390"}],"wp:attachment":[{"href":"https:\/\/asso-sozen.com\/index.php\/wp-json\/wp\/v2\/media?parent=839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/asso-sozen.com\/index.php\/wp-json\/wp\/v2\/categories?post=839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/asso-sozen.com\/index.php\/wp-json\/wp\/v2\/tags?post=839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}